{"id":72164,"date":"2026-03-22T01:00:00","date_gmt":"2026-03-22T00:00:00","guid":{"rendered":"https:\/\/freestuff.world\/freebie\/pages-de-coloriage-de-paques-imprimables-et-gratuites\/"},"modified":"2026-03-31T13:42:59","modified_gmt":"2026-03-31T12:42:59","slug":"pages-de-coloriage-de-paques-imprimables-et-gratuites","status":"publish","type":"freebie","link":"https:\/\/freestuff.world\/fr\/freebie\/pages-de-coloriage-de-paques-imprimables-et-gratuites\/","title":{"rendered":"Pages de coloriage de P\u00e2ques imprimables et gratuites"},"content":{"rendered":"<p>Si vous cherchez une activit\u00e9 de P\u00e2ques amusante et gratuite pour votre famille, cette offre est parfaite. Vous pouvez obtenir des pages de coloriage de P\u00e2ques imprimables gratuitement. Le choix est vaste : paniers de P\u00e2ques, lapins, canards, \u0153ufs, etc. Si vous voulez quelque chose qui s&rsquo;inspire de la religion chr\u00e9tienne, il y a aussi des pages de coloriage pour cette religion, de sorte qu&rsquo;il y a une grande vari\u00e9t\u00e9 de dessins pour l&rsquo;occasion.   <\/p>\n<p>Cliquez sur le bouton vert ci-dessous pour visiter Raising Our Kids, o\u00f9 vous trouverez les pages de coloriage gratuites. Il vous suffit de choisir les dessins que vous voulez, de cliquer dessus et de les imprimer. Profitez d&rsquo;une journ\u00e9e de bricolage amusante et gratuite avec votre famille.  <\/p>\n","protected":false},"featured_media":71683,"template":"","categories":[84,381,351,184,217,317,85,238,289,128,88,83,262,185,331,87,126,86,246,89,127,221,191,224,372,321,123,192],"tags":[],"mobile-category":[273,380,350,272,203,201,204,215,205,312,274,214,206,231,309,207,371,330,208,285,209,202,210,211,270,213,212,200],"label":[],"class_list":["post-72164","freebie","type-freebie","status-publish","has-post-thumbnail","hentry","category-international-fr","category--autriche-freebies","category--belgique-freebies","category--choses-gratuites-en-malaisie","category--des-choses-gratuites-en-allemagne","category--echantillons-et-produits-gratuits-en-inde","category-canada-fr","category--echantillons-gratuits-au-mexique","category-echantillons-gratuits-au-portugal","category-pologne","category-hong-kong-fr","category-singapour","category--freebies-au-bresil","category-freebies-aux-emirats-arabes-unis","category--freebies-aux-philippines","category-usa-fr","category--freebies-disponibles-au-nigeria","category-afrique-du-sud","category--freebies-en-argentine","category-espagne","category-france-fr","category--freebies-en-indonesie","category--freebies-en-italie","category--freebies-en-suisse","category--gratuit-en-norvege","category--netherlands-free-stuff","category-suede","category--republique-tcheque-freebies","mobile-category-argentina","mobile-category-austria","mobile-category-belgium","mobile-category-brazil","mobile-category-canada","mobile-category-czech-republic","mobile-category-france","mobile-category-germany","mobile-category-hong-kong","mobile-category-india","mobile-category-indonesia","mobile-category-italy","mobile-category-malaysia","mobile-category-mexico","mobile-category-netherlands","mobile-category-nigeria","mobile-category-norway","mobile-category-philippines","mobile-category-poland","mobile-category-portugal","mobile-category-singapore","mobile-category-south-africa","mobile-category-spain","mobile-category-sweden","mobile-category-switzerland","mobile-category-uae","mobile-category-usa","mobile-category-worldwide"],"featured_image_src":"https:\/\/cdn.freestuff.world\/wp-content\/uploads\/2026\/03\/71681.jpeg?strip=all","ams_acf":[],"wpcf-offer-link":"https:\/\/www.raisingourkids.com\/coloring-pages\/holiday\/easter\/","wpcf-does-the-offer-relate-to-gambling":"1","wpcf-exclude-republish":"0","wpcf-force-republish":null,"wpcf-exclude-email":null,"wpcf-individual-listing-id":null,"wpcf-include-social":null,"wpcf-social-template":null,"wpcf-expire-but-live":null,"_wow_auto_republish_settings":null,"wpcf-subject-line":null,"wpcf-intro-text":null,"wpcf-custom-text":null,"wpcf-custom-cta":null,"_wow_auto_republish_enabled":null,"wpcf-affiliate-network":"notprofit","_wpscp_schedule_draft_date":null,"_wpscp_schedule_republish_date":null,"wpcf-note":"","wpcf-network-offer-name":"","affiliate_network":"notprofit","toolset-meta":{"solo-email-settings":{"subject-line":{"type":"textfield","raw":""},"intro-text":{"type":"textarea","raw":""},"custom-text":{"type":"textarea","raw":""},"custom-cta":{"type":"textfield","raw":""}},"universal-link-settings":{"individual-listing-id":{"type":"textarea","raw":""}},"notes":{"note":{"type":"textarea","raw":""}},"exposure":{"featured":{"type":"checkbox","raw":"0"},"force-republish":{"type":"checkbox","raw":""},"exclude-republish":{"type":"checkbox","raw":"0"},"force-email":{"type":"checkbox","raw":""},"exclude-email":{"type":"checkbox","raw":""},"include-social":{"type":"checkbox","raw":""},"social-template":{"type":"textarea","raw":""},"force-social":{"type":"checkbox","raw":""},"hide-on-mobile":{"type":"checkbox","raw":""},"organic-traffic":{"type":"checkbox","raw":""},"expire-but-live":{"type":"checkbox","raw":""}},"offer-information":{"offer-link":{"type":"url","raw":"https:\/\/www.raisingourkids.com\/coloring-pages\/holiday\/easter\/"},"affiliate-network":{"type":"select","raw":"notprofit"},"network-offer-name":{"type":"textfield","raw":""},"account-manager":{"type":"email","raw":""},"does-the-offer-relate-to-gambling":{"type":"select","raw":"1"},"seasonal":{"type":"select","raw":""},"requires-approval":{"type":"checkbox","raw":""}}},"_links":{"self":[{"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/freebie\/72164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/freebie"}],"about":[{"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/types\/freebie"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/media\/71683"}],"wp:attachment":[{"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/media?parent=72164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/categories?post=72164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/tags?post=72164"},{"taxonomy":"mobile-category","embeddable":true,"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/mobile-category?post=72164"},{"taxonomy":"label","embeddable":true,"href":"https:\/\/freestuff.world\/fr\/wp-json\/wp\/v2\/label?post=72164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}